{"id":1350,"count":1,"description":"","link":"https:\/\/www.culmia.com\/es\/provincia\/madrid\/pozuelo-de-alarcon\/","name":"Pozuelo de Alarc\u00f3n","slug":"pozuelo-de-alarcon","taxonomy":"provincia","parent":109,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia\/1350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia"}],"about":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/taxonomies\/provincia"}],"up":[{"embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia\/109"}],"wp:post_type":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/promociones?provincia=1350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}