{"id":1340,"count":1,"description":"","link":"https:\/\/www.culmia.com\/es\/provincia\/pontevedra\/sanxenxo\/","name":"Sanxenxo","slug":"sanxenxo","taxonomy":"provincia","parent":151,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia\/1340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia"}],"about":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/taxonomies\/provincia"}],"up":[{"embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/provincia\/151"}],"wp:post_type":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/promociones?provincia=1340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}