{"id":6263,"date":"2024-04-19T07:32:54","date_gmt":"2024-04-19T07:32:54","guid":{"rendered":"https:\/\/www.culmia.com\/blog\/?p=6263"},"modified":"2025-10-02T13:13:41","modified_gmt":"2025-10-02T11:13:41","slug":"boarding-pass-con-carles-olmos-2","status":"publish","type":"post","link":"https:\/\/www.culmia.com\/es\/blog\/boarding-pass-con-carles-olmos-2\/","title":{"rendered":"Boarding Pass con Carles Olmos"},"content":{"rendered":"<div class=\"css-1dbjc4n\"> <div class=\"css-1dbjc4n r-1s2bzr4\"> <div id=\"id__msv09l9wvh\" class=\"css-901oao r-18jsvk2 r-37j5jr r-1blvdjr r-16dba41 r-vrz42v r-bcqeeo r-bnwqim r-qvutc0\" dir=\"auto\" lang=\"es\" data-testid=\"tweetText\"> <p>Carles Olmos, Delegado de Estrategia Comercial, ha sido el encargado de participar en un nuevo episodio de Boarding Pass en la secci\u00f3n de Capital Radio<\/p> <p>Ha presentado la primera promoci\u00f3n de Culmia en Palma de Mallorca, Can Mare. Se trata de una promoci\u00f3n de 88 viviendas, que arquitect\u00f3nicamente tiene forma de U. Es un edificio de cuatro plantas y bajos, con una zona comunitaria en el centro.<\/p> <\/div> <div id=\"id__msv09l9wvh\" class=\"css-901oao r-18jsvk2 r-37j5jr r-1blvdjr r-16dba41 r-vrz42v r-bcqeeo r-bnwqim r-qvutc0\" dir=\"auto\" lang=\"es\" data-testid=\"tweetText\"> <p>En cuanto a las tipolog\u00edas de vivienda, son de 2, 3 y 4 dormitorios, que van desde 60 m2 a 100 m2 \u00fatiles y todas las viviendas cuentan con terrazas y balcones.<\/p> <p>Las plantas bajas cuentan con unas terrazas muy amplias,\u00a0 desde 55 m2 a 220 m2 y las cuartas plantas tienen una terraza privada de entre 38 m2 a\u00a0 70 m2.<\/p> <p>En su dise\u00f1o se han tenido en cuenta los voladizos para hacer de protecci\u00f3n solar, la ventilaci\u00f3n natural y la carpinter\u00eda con rotura de puente t\u00e9rmico y doble acristalamiento. Otra cosa muy importante a resaltar, es que\u00a0 todas las viviendas tiene una plaza de aparcamiento y trastero.<\/p> <\/div> <\/div> <div class=\"css-1dbjc4n r-1s2bzr4\"> <p>\u00bfQu\u00e9 te parece la promoci\u00f3n Can Mare?<\/p> <div id=\"id__msv09l9wvh\" class=\"css-901oao r-18jsvk2 r-37j5jr r-1blvdjr r-16dba41 r-vrz42v r-bcqeeo r-bnwqim r-qvutc0\" dir=\"auto\" lang=\"es\" data-testid=\"tweetText\"> <p>#CapitalRadio #Promociones #ObraNueva #Inversi\u00f3nInmobiliaria<\/p> <\/div> <\/div> <\/div> <div class=\"powerpress_player\" id=\"powerpress_player_6995\"><audio class=\"wp-audio-shortcode\" id=\"audio-6263-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.culmia.com\/wp-content\/uploads\/2024\/04\/20240418_INVERSION_INMOBILIARIA_1-mp3cut.net_.mp3?_=1\" \/><a href=\"https:\/\/www.culmia.com\/wp-content\/uploads\/2024\/04\/20240418_INVERSION_INMOBILIARIA_1-mp3cut.net_.mp3\">https:\/\/www.culmia.com\/wp-content\/uploads\/2024\/04\/20240418_INVERSION_INMOBILIARIA_1-mp3cut.net_.mp3<\/a><\/audio><\/div>","protected":false},"excerpt":{"rendered":"<p>Carles Olmos, Delegado de Estrategia Comercial, ha sido el encargado &#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[242],"tags":[243],"class_list":["post-6263","post","type-post","status-publish","format-standard","hentry","category-podcast","tag-podcast-culmia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/posts\/6263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/comments?post=6263"}],"version-history":[{"count":1,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/posts\/6263\/revisions"}],"predecessor-version":[{"id":26147,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/posts\/6263\/revisions\/26147"}],"wp:attachment":[{"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/media?parent=6263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/categories?post=6263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culmia.com\/es\/wp-json\/wp\/v2\/tags?post=6263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}